{"id":3595,"date":"2026-08-31T17:11:00","date_gmt":"2026-08-31T17:11:00","guid":{"rendered":"https:\/\/sinaloainformativo.com\/?p=3595"},"modified":"2026-09-01T17:20:21","modified_gmt":"2026-09-01T17:20:21","slug":"ingenierias-de-la-fcqb-de-la-uas-ingresan-al-padron-de-alto-rendimiento-academico-del-egel-ceneval-se-avala-la-alta-competitividad-nacional-e-internacional-de-sus-egresados","status":"publish","type":"post","link":"https:\/\/sinaloainformativo.com\/index.php\/2026\/08\/31\/ingenierias-de-la-fcqb-de-la-uas-ingresan-al-padron-de-alto-rendimiento-academico-del-egel-ceneval-se-avala-la-alta-competitividad-nacional-e-internacional-de-sus-egresados\/","title":{"rendered":"Ingenier\u00edas de la FCQB de la UAS ingresan al Padr\u00f3n de Alto Rendimiento Acad\u00e9mico del EGEL-Ceneval; se avala la alta competitividad nacional e internacional de sus egresados"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/sinaloainformativo.com\/wp-content\/uploads\/2026\/09\/grande_034425001788182872-1024x682.jpeg\" alt=\"\" class=\"wp-image-3596\" style=\"aspect-ratio:1.501487754634928;width:417px;height:auto\" srcset=\"https:\/\/sinaloainformativo.com\/wp-content\/uploads\/2026\/09\/grande_034425001788182872-1024x682.jpeg 1024w, https:\/\/sinaloainformativo.com\/wp-content\/uploads\/2026\/09\/grande_034425001788182872-300x200.jpeg 300w, https:\/\/sinaloainformativo.com\/wp-content\/uploads\/2026\/09\/grande_034425001788182872-768x512.jpeg 768w, https:\/\/sinaloainformativo.com\/wp-content\/uploads\/2026\/09\/grande_034425001788182872.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las Licenciaturas en Ingenier\u00eda Qu\u00edmica e Ingenier\u00eda Bioqu\u00edmica de la Facultad de Ciencias Qu\u00edmico-Biol\u00f3gicas (FCQB) de la Universidad Aut\u00f3noma de Sinaloa (UAS) consolidaron su calidad acad\u00e9mica a nivel nacional al ingresar formalmente al Padr\u00f3n de Programas de Licenciatura de Alto Rendimiento Acad\u00e9mico del EGEL-Ceneval. Este logro posiciona a ambas carreras dentro de un selecto grupo de programas de educaci\u00f3n superior en M\u00e9xico, destac\u00f3 el doctor Eusiel Rubio Castro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El director de la facultad afirm\u00f3 que este reconocimiento avala que la gran mayor\u00eda de sus egresados alcanzan niveles de excelencia en el Examen General para el Egreso de Licenciatura (EGEL). Asimismo, se\u00f1al\u00f3 que este nombramiento es un refrendo a la labor institucional, ya que desde el a\u00f1o 2012 se ha trabajado de manera ininterrumpida en este rubro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cInternamente, para la Facultad de Ciencias Qu\u00edmico-Biol\u00f3gicas representa un resultado que demuestra el compromiso en la formaci\u00f3n y calidad de nuestros egresados y egresadas, particularmente en estos dos programas educativos\u201d, enfatiz\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acad\u00e9mico universitario destac\u00f3 que en la UAS solo estos dos programas han obtenido dicha distinci\u00f3n, lo que representa un sello de garant\u00eda institucional que coloca a la universidad a la par de las mejores del pa\u00eds. Subray\u00f3 tambi\u00e9n que el logro es resultado del desempe\u00f1o sobresaliente de los estudiantes, la alta habilitaci\u00f3n de la planta docente y la constante actualizaci\u00f3n de los planes de estudio y laboratorios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn el caso espec\u00edfico de estas dos licenciaturas, el criterio de ingreso se basa en los porcentajes de testimonios sobresalientes y satisfactorios de sus egresados. Espec\u00edficamente, en la Licenciatura en Ingenier\u00eda Bioqu\u00edmica se obtuvo el Nivel 1, dado que m\u00e1s del 90 % de sus egresados obtuvieron un testimonio satisfactorio. En el caso de Ingenier\u00eda Qu\u00edmica se obtuvo el Nivel 2, dado que entre el 70 % y el 90 % alcanz\u00f3 un nivel satisfactorio en su examen\u201d, detall\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, manifest\u00f3 que con este ingreso al Padr\u00f3n EGEL-Ceneval, la UAS refrenda el impacto y la competitividad de sus egresados en el mercado laboral. Asegur\u00f3 que los profesionales de la qu\u00edmica y la bioqu\u00edmica formados en las aulas rosalinas cuentan con las competencias id\u00f3neas para incorporarse con \u00e9xito a los sectores industrial, farmac\u00e9utico y biotecnol\u00f3gico, tanto nacional como internacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Licenciaturas en Ingenier\u00eda Qu\u00edmica e Ingenier\u00eda Bioqu\u00edmica de la Facultad de Ciencias Qu\u00edmico-Biol\u00f3gicas (FCQB) de la Universidad Aut\u00f3noma de Sinaloa (UAS) consolidaron su calidad acad\u00e9mica a nivel nacional al ingresar formalmente al Padr\u00f3n de Programas de Licenciatura de Alto Rendimiento Acad\u00e9mico del EGEL-Ceneval. Este logro posiciona a ambas carreras dentro de un selecto grupo &#8230; <a title=\"Ingenier\u00edas de la FCQB de la UAS ingresan al Padr\u00f3n de Alto Rendimiento Acad\u00e9mico del EGEL-Ceneval; se avala la alta competitividad nacional e internacional de sus egresados\" class=\"read-more\" href=\"https:\/\/sinaloainformativo.com\/index.php\/2026\/08\/31\/ingenierias-de-la-fcqb-de-la-uas-ingresan-al-padron-de-alto-rendimiento-academico-del-egel-ceneval-se-avala-la-alta-competitividad-nacional-e-internacional-de-sus-egresados\/\" aria-label=\"M\u00e1s en Ingenier\u00edas de la FCQB de la UAS ingresan al Padr\u00f3n de Alto Rendimiento Acad\u00e9mico del EGEL-Ceneval; se avala la alta competitividad nacional e internacional de sus egresados\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":3598,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/sinaloainformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/3595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinaloainformativo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sinaloainformativo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sinaloainformativo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sinaloainformativo.com\/index.php\/wp-json\/wp\/v2\/comments?post=3595"}],"version-history":[{"count":1,"href":"https:\/\/sinaloainformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/3595\/revisions"}],"predecessor-version":[{"id":3597,"href":"https:\/\/sinaloainformativo.com\/index.php\/wp-json\/wp\/v2\/posts\/3595\/revisions\/3597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sinaloainformativo.com\/index.php\/wp-json\/wp\/v2\/media\/3598"}],"wp:attachment":[{"href":"https:\/\/sinaloainformativo.com\/index.php\/wp-json\/wp\/v2\/media?parent=3595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sinaloainformativo.com\/index.php\/wp-json\/wp\/v2\/categories?post=3595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sinaloainformativo.com\/index.php\/wp-json\/wp\/v2\/tags?post=3595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}